{"id":17077,"date":"2016-02-18T18:49:21","date_gmt":"2016-02-18T17:49:21","guid":{"rendered":"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg"},"modified":"2016-02-18T18:49:21","modified_gmt":"2016-02-18T17:49:21","slug":"villa-punto-de-vista-7","status":"inherit","type":"attachment","link":"https:\/\/www.themilliardaire.com\/en\/villas\/villa-punto-de-vista-17070\/attachment\/villa-punto-de-vista-7\/","title":{"rendered":"Villa-Punto-de-Vista-7"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-17077","attachment","type-attachment","status-inherit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Villa-Punto-de-Vista-7 - THE MILLIARDAIRE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa-Punto-de-Vista-7 - THE MILLIARDAIRE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg\" \/>\n<meta property=\"og:site_name\" content=\"THE MILLIARDAIRE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheMilliardaire\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"879\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@themilliardaire\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Villa-Punto-de-Vista-7.jpg\",\"url\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Villa-Punto-de-Vista-7.jpg\",\"name\":\"Villa-Punto-de-Vista-7 - THE MILLIARDAIRE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/#website\"},\"datePublished\":\"2016-02-18T17:49:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Villa-Punto-de-Vista-7.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Villa-Punto-de-Vista-7.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Villa-Punto-de-Vista-7.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Villa Punto de Vista: a private luxury villa for demanding travelers in Costa Rica\",\"item\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/villas\\\/villa-punto-de-vista-17070\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Villa-Punto-de-Vista-7\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/\",\"name\":\"THE MILLIARDAIRE\",\"description\":\"Online luxury magazine - TheMilliardaire\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Villa-Punto-de-Vista-7 - THE MILLIARDAIRE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg","og_locale":"en_US","og_type":"article","og_title":"Villa-Punto-de-Vista-7 - THE MILLIARDAIRE","og_url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg","og_site_name":"THE MILLIARDAIRE","article_publisher":"https:\/\/www.facebook.com\/TheMilliardaire\/","og_image":[{"width":1300,"height":879,"url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@themilliardaire","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg","url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg","name":"Villa-Punto-de-Vista-7 - THE MILLIARDAIRE","isPartOf":{"@id":"https:\/\/www.themilliardaire.com\/en\/#website"},"datePublished":"2016-02-18T17:49:21+00:00","breadcrumb":{"@id":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.themilliardaire.com\/en\/"},{"@type":"ListItem","position":2,"name":"Villa Punto de Vista: a private luxury villa for demanding travelers in Costa Rica","item":"https:\/\/www.themilliardaire.com\/en\/villas\/villa-punto-de-vista-17070\/"},{"@type":"ListItem","position":3,"name":"Villa-Punto-de-Vista-7"}]},{"@type":"WebSite","@id":"https:\/\/www.themilliardaire.com\/en\/#website","url":"https:\/\/www.themilliardaire.com\/en\/","name":"THE MILLIARDAIRE","description":"Online luxury magazine - TheMilliardaire","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.themilliardaire.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"203\" src=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-300x203.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-300x203.jpg 300w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-768x519.jpg 768w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-1024x692.jpg 1024w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-600x406.jpg 600w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-422x285.jpg 422w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg 1300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1300,"height":879,"file":"2016\/02\/Villa-Punto-de-Vista-7.jpg","sizes":{"thumbnail":{"file":"Villa-Punto-de-Vista-7-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-150x150.jpg"},"medium":{"file":"Villa-Punto-de-Vista-7-300x203.jpg","width":300,"height":203,"mime_type":"image\/jpeg","source_url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-300x203.jpg"},"medium_large":{"file":"Villa-Punto-de-Vista-7-768x519.jpg","width":768,"height":519,"mime_type":"image\/jpeg","source_url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-768x519.jpg"},"large":{"file":"Villa-Punto-de-Vista-7-1024x692.jpg","width":1024,"height":692,"mime_type":"image\/jpeg","source_url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-1024x692.jpg"},"wysija-newsletters-max":{"file":"Villa-Punto-de-Vista-7-600x406.jpg","width":600,"height":406,"mime_type":"image\/jpeg","source_url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-600x406.jpg"},"home":{"file":"Villa-Punto-de-Vista-7-590x387.jpg","width":590,"height":387,"mime_type":"image\/jpeg","source_url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-590x387.jpg"},"vignette":{"file":"Villa-Punto-de-Vista-7-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-300x200.jpg"},"vignetteL":{"file":"Villa-Punto-de-Vista-7-600x200.jpg","width":600,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-600x200.jpg"},"picthumb":{"file":"Villa-Punto-de-Vista-7-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-300x300.jpg"},"search":{"file":"Villa-Punto-de-Vista-7-422x285.jpg","width":422,"height":285,"mime_type":"image\/jpeg","source_url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7-422x285.jpg"},"full":{"file":"Villa-Punto-de-Vista-7.jpg","width":1300,"height":879,"mime_type":"image\/jpeg","source_url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg"}},"image_meta":{"aperture":"14","credit":"","camera":"NIKON D800","caption":"","created_timestamp":"1366269477","copyright":"","focal_length":"50","iso":"320","shutter_speed":"0.039990002499375","title":"","orientation":"1","keywords":["hdr process"]}},"post":17070,"source_url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2016\/02\/Villa-Punto-de-Vista-7.jpg","_links":{"self":[{"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/media\/17077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/comments?post=17077"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":17070,"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/posts\/17070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}