{"id":6945,"date":"2013-09-30T09:33:23","date_gmt":"2013-09-30T08:33:23","guid":{"rendered":"http:\/\/www.themilliardaire.com\/en\/\/?p=6945"},"modified":"2013-11-04T14:09:07","modified_gmt":"2013-11-04T14:09:07","slug":"the-wandana-residence-space-and-design","status":"publish","type":"post","link":"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/","title":{"rendered":"The Wandana Residence, space and design"},"content":{"rendered":"<p>Designed by James Deans & Associates, <strong>The Wandana Residence<\/strong> offers a splendid view on Geelong\u2019s suburbs, located in the city of Victoria, Australia.<\/p>\n<h2 id=\"the-wandana-residence-a-subtle-mixture\">The Wandana Residence, a subtle mixture<\/h2>\n<p><strong>The Wandana Residence<\/strong> was created following an architecture plan based on natural light by the floor and to the windows combined. There is a blending aestheticism of a hotel and the peace of a family home. This spirit allows associating art\u2019s simplicity without losing a real dimension.<\/p>\n<p>The house offers as well spaces that satisfy a family\u2019s vital needs. The kitchen was made the intelligent way and the presented glasses are dazzling. In the house\u2019s rear, a terrace that you can access through sliding doors will comfort you with a sunny moment of relaxation. This residence is filled with a feeling of welfare. Its spaces foster the family\u2019s incredible place.<\/p>\n<p>A garden of 700 square meters that supplies a panoramic view on Geelong. Tennis courts, a playground and a football stadium come to complete this panoply of elements that make the <strong>Wandana Residence<\/strong> a unique place.<\/p>\n<p>A sober house with features and a minimalist style. Atmosphere and relaxation will, for sure, be part of the experience!<\/p>\n<p><a href=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-Residence-piscine.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6946\" alt=\"piscine maison\" src=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-Residence-piscine.jpg\" width=\"1100\" height=\"732\" srcset=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-piscine.jpg 1100w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-piscine-300x200.jpg 300w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-piscine-1024x681.jpg 1024w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-piscine-600x399.jpg 600w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-piscine-428x285.jpg 428w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/a> <a href=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/wandana-deisgn.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6947\" alt=\"vue nuit villa\" src=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/wandana-deisgn.jpg\" width=\"1100\" height=\"732\" srcset=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/wandana-deisgn.jpg 1100w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/wandana-deisgn-300x200.jpg 300w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/wandana-deisgn-1024x681.jpg 1024w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/wandana-deisgn-600x399.jpg 600w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/wandana-deisgn-428x285.jpg 428w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/a> <a href=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-Residence-interieur.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6948\" alt=\"espace salon exterieur\" src=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-Residence-interieur.jpg\" width=\"1100\" height=\"732\" srcset=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-interieur.jpg 1100w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-interieur-300x200.jpg 300w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-interieur-1024x681.jpg 1024w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-interieur-600x399.jpg 600w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-interieur-428x285.jpg 428w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/a> <a href=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-Residence-terrasse.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6949\" alt=\"terrasse maison\" src=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-Residence-terrasse.jpg\" width=\"1100\" height=\"732\" srcset=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-terrasse.jpg 1100w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-terrasse-300x200.jpg 300w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-terrasse-1024x681.jpg 1024w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-terrasse-600x399.jpg 600w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-terrasse-428x285.jpg 428w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/a> <a href=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-Residence-vue-de-nuit.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6950\" alt=\"piscine exterieure\" src=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-Residence-vue-de-nuit.jpg\" width=\"1100\" height=\"732\" srcset=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-vue-de-nuit.jpg 1100w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-vue-de-nuit-300x200.jpg 300w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-vue-de-nuit-1024x681.jpg 1024w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-vue-de-nuit-600x399.jpg 600w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-vue-de-nuit-428x285.jpg 428w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/a> <a href=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-Residence-hall.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6951\" alt=\"couloir maison\" src=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-Residence-hall.jpg\" width=\"1100\" height=\"732\" srcset=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-hall.jpg 1100w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-hall-300x200.jpg 300w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-hall-1024x681.jpg 1024w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-hall-600x399.jpg 600w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-hall-428x285.jpg 428w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/a> <a href=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-house.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6952\" alt=\"villa int\u00e9rieur\" src=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-house.jpg\" width=\"1100\" height=\"732\" srcset=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-house.jpg 1100w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-house-300x200.jpg 300w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-house-1024x681.jpg 1024w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-house-600x399.jpg 600w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-house-428x285.jpg 428w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/a> <a href=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-Residence-salon.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6953\" alt=\"salon espace\" src=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-Residence-salon.jpg\" width=\"1100\" height=\"732\" srcset=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-salon.jpg 1100w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-salon-300x200.jpg 300w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-salon-1024x681.jpg 1024w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-salon-600x399.jpg 600w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-salon-428x285.jpg 428w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/a> <a href=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-Residence-vue-exterieure.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6954\" alt=\"nuit maison\" src=\"http:\/\/www.themilliardaire.com\/en\/\/wp-content\/uploads\/2013\/09\/Wandana-Residence-vue-exterieure.jpg\" width=\"1100\" height=\"732\" srcset=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-vue-exterieure.jpg 1100w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-vue-exterieure-300x200.jpg 300w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-vue-exterieure-1024x681.jpg 1024w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-vue-exterieure-600x399.jpg 600w, https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/Wandana-Residence-vue-exterieure-428x285.jpg 428w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/a><\/p>\n[button size=\u201dsmall\u201d color=\u201dblack\u201d style=\u201dnone\u201d new_window=\u201dtrue\u201d link=\u201dhttp:\/\/www.jdarchitects.com.au\/\u201d]More information on the constructor\u2019s website[\/button]\n","protected":false},"excerpt":{"rendered":"Designed by James Deans &#038; Associates, The Wandana Residence offers a splendid view on Geelong\u2019s suburbs, located in&hellip;\n","protected":false},"author":1,"featured_media":6955,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[26],"tags":[109,1332,1331,73,187],"class_list":{"0":"post-6945","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-design","8":"tag-architecture","9":"tag-art","10":"tag-design","11":"tag-luxe","12":"tag-villa"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Wandana Residence, space and design - THE MILLIARDAIRE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Wandana Residence, space and design - THE MILLIARDAIRE\" \/>\n<meta property=\"og:description\" content=\"Designed by James Deans &amp; Associates, The Wandana Residence offers a splendid view on Geelong\u2019s suburbs, located in&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/\" \/>\n<meta property=\"og:site_name\" content=\"THE MILLIARDAIRE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheMilliardaire\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-30T08:33:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-11-04T14:09:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/design-villa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"732\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"TheMilliardaire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@themilliardaire\" \/>\n<meta name=\"twitter:site\" content=\"@themilliardaire\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"TheMilliardaire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/design\\\/the-wandana-residence-space-and-design-6945\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/design\\\/the-wandana-residence-space-and-design-6945\\\/\"},\"author\":{\"name\":\"TheMilliardaire\",\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/#\\\/schema\\\/person\\\/44c252d5e26890d7ef63b70ad7e7572b\"},\"headline\":\"The Wandana Residence, space and design\",\"datePublished\":\"2013-09-30T08:33:23+00:00\",\"dateModified\":\"2013-11-04T14:09:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/design\\\/the-wandana-residence-space-and-design-6945\\\/\"},\"wordCount\":228,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/design\\\/the-wandana-residence-space-and-design-6945\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/design-villa.jpg\",\"keywords\":[\"Architecture\",\"Art\",\"Design\",\"Luxe\",\"Villa\"],\"articleSection\":[\"Design\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/design\\\/the-wandana-residence-space-and-design-6945\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/design\\\/the-wandana-residence-space-and-design-6945\\\/\",\"url\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/design\\\/the-wandana-residence-space-and-design-6945\\\/\",\"name\":\"The Wandana Residence, space and design - THE MILLIARDAIRE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/design\\\/the-wandana-residence-space-and-design-6945\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/design\\\/the-wandana-residence-space-and-design-6945\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/design-villa.jpg\",\"datePublished\":\"2013-09-30T08:33:23+00:00\",\"dateModified\":\"2013-11-04T14:09:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/#\\\/schema\\\/person\\\/44c252d5e26890d7ef63b70ad7e7572b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/design\\\/the-wandana-residence-space-and-design-6945\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/design\\\/the-wandana-residence-space-and-design-6945\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/design\\\/the-wandana-residence-space-and-design-6945\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/design-villa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/design-villa.jpg\",\"width\":1100,\"height\":732},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/design\\\/the-wandana-residence-space-and-design-6945\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Wandana Residence, space and design\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/\",\"name\":\"THE MILLIARDAIRE\",\"description\":\"Online luxury magazine - TheMilliardaire\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.themilliardaire.com\\\/en\\\/#\\\/schema\\\/person\\\/44c252d5e26890d7ef63b70ad7e7572b\",\"name\":\"TheMilliardaire\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57417f1540dd14d56127bb0305a8c69db79b2d0fe77a875207f733c8c5701ffd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57417f1540dd14d56127bb0305a8c69db79b2d0fe77a875207f733c8c5701ffd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57417f1540dd14d56127bb0305a8c69db79b2d0fe77a875207f733c8c5701ffd?s=96&d=mm&r=g\",\"caption\":\"TheMilliardaire\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Wandana Residence, space and design - THE MILLIARDAIRE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/","og_locale":"en_US","og_type":"article","og_title":"The Wandana Residence, space and design - THE MILLIARDAIRE","og_description":"Designed by James Deans & Associates, The Wandana Residence offers a splendid view on Geelong\u2019s suburbs, located in&hellip;","og_url":"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/","og_site_name":"THE MILLIARDAIRE","article_publisher":"https:\/\/www.facebook.com\/TheMilliardaire\/","article_published_time":"2013-09-30T08:33:23+00:00","article_modified_time":"2013-11-04T14:09:07+00:00","og_image":[{"width":1100,"height":732,"url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/design-villa.jpg","type":"image\/jpeg"}],"author":"TheMilliardaire","twitter_card":"summary_large_image","twitter_creator":"@themilliardaire","twitter_site":"@themilliardaire","twitter_misc":{"Written by":"TheMilliardaire","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/#article","isPartOf":{"@id":"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/"},"author":{"name":"TheMilliardaire","@id":"https:\/\/www.themilliardaire.com\/en\/#\/schema\/person\/44c252d5e26890d7ef63b70ad7e7572b"},"headline":"The Wandana Residence, space and design","datePublished":"2013-09-30T08:33:23+00:00","dateModified":"2013-11-04T14:09:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/"},"wordCount":228,"commentCount":0,"image":{"@id":"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/#primaryimage"},"thumbnailUrl":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/design-villa.jpg","keywords":["Architecture","Art","Design","Luxe","Villa"],"articleSection":["Design"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/","url":"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/","name":"The Wandana Residence, space and design - THE MILLIARDAIRE","isPartOf":{"@id":"https:\/\/www.themilliardaire.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/#primaryimage"},"image":{"@id":"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/#primaryimage"},"thumbnailUrl":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/design-villa.jpg","datePublished":"2013-09-30T08:33:23+00:00","dateModified":"2013-11-04T14:09:07+00:00","author":{"@id":"https:\/\/www.themilliardaire.com\/en\/#\/schema\/person\/44c252d5e26890d7ef63b70ad7e7572b"},"breadcrumb":{"@id":"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/#primaryimage","url":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/design-villa.jpg","contentUrl":"https:\/\/www.themilliardaire.com\/en\/wp-content\/uploads\/2013\/09\/design-villa.jpg","width":1100,"height":732},{"@type":"BreadcrumbList","@id":"https:\/\/www.themilliardaire.com\/en\/design\/the-wandana-residence-space-and-design-6945\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.themilliardaire.com\/en\/"},{"@type":"ListItem","position":2,"name":"The Wandana Residence, space and design"}]},{"@type":"WebSite","@id":"https:\/\/www.themilliardaire.com\/en\/#website","url":"https:\/\/www.themilliardaire.com\/en\/","name":"THE MILLIARDAIRE","description":"Online luxury magazine - TheMilliardaire","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.themilliardaire.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.themilliardaire.com\/en\/#\/schema\/person\/44c252d5e26890d7ef63b70ad7e7572b","name":"TheMilliardaire","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/57417f1540dd14d56127bb0305a8c69db79b2d0fe77a875207f733c8c5701ffd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57417f1540dd14d56127bb0305a8c69db79b2d0fe77a875207f733c8c5701ffd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57417f1540dd14d56127bb0305a8c69db79b2d0fe77a875207f733c8c5701ffd?s=96&d=mm&r=g","caption":"TheMilliardaire"}}]}},"_links":{"self":[{"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/posts\/6945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/comments?post=6945"}],"version-history":[{"count":4,"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/posts\/6945\/revisions"}],"predecessor-version":[{"id":7525,"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/posts\/6945\/revisions\/7525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/media\/6955"}],"wp:attachment":[{"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/media?parent=6945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/categories?post=6945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.themilliardaire.com\/en\/wp-json\/wp\/v2\/tags?post=6945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}